{"id":619,"count":1,"description":"","link":"https:\/\/www.codental.com.br\/blog\/tag\/nervo-hipoglosso\/","name":"Nervo hipoglosso","slug":"nervo-hipoglosso","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Arquivos Nervo hipoglosso - Codental Blog<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Arquivos Nervo hipoglosso - Codental Blog\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.codental.com.br\/blog\/tag\/nervo-hipoglosso\/\" \/>\n<meta property=\"og:site_name\" content=\"Codental Blog\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@CodentalBr\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/www.codental.com.br\/blog\/tag\/nervo-hipoglosso\/\",\"url\":\"https:\/\/www.codental.com.br\/blog\/tag\/nervo-hipoglosso\/\",\"name\":\"Arquivos Nervo hipoglosso - Codental Blog\",\"isPartOf\":{\"@id\":\"https:\/\/www.codental.com.br\/blog\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.codental.com.br\/blog\/tag\/nervo-hipoglosso\/#breadcrumb\"},\"inLanguage\":\"pt-BR\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.codental.com.br\/blog\/tag\/nervo-hipoglosso\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.codental.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nervo hipoglosso\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.codental.com.br\/blog\/#website\",\"url\":\"https:\/\/www.codental.com.br\/blog\/\",\"name\":\"Codental Blog\",\"description\":\"Artigos e not\u00edcias sobre odontologia\",\"publisher\":{\"@id\":\"https:\/\/www.codental.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.codental.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.codental.com.br\/blog\/#organization\",\"name\":\"Codental\",\"url\":\"https:\/\/codental.com.br\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.codental.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.codental.com.br\/blog\/wp-content\/uploads\/2018\/10\/logo.png\",\"contentUrl\":\"https:\/\/www.codental.com.br\/blog\/wp-content\/uploads\/2018\/10\/logo.png\",\"width\":1200,\"height\":300,\"caption\":\"Codental\"},\"image\":{\"@id\":\"https:\/\/www.codental.com.br\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"http:\/\/www.facebook.com\/codentalbr\",\"https:\/\/x.com\/CodentalBr\",\"https:\/\/www.instagram.com\/codentalbr\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Arquivos Nervo hipoglosso - Codental Blog","robots":{"index":"noindex","follow":"follow"},"og_locale":"pt_BR","og_type":"article","og_title":"Arquivos Nervo hipoglosso - Codental Blog","og_url":"https:\/\/www.codental.com.br\/blog\/tag\/nervo-hipoglosso\/","og_site_name":"Codental Blog","twitter_card":"summary_large_image","twitter_site":"@CodentalBr","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.codental.com.br\/blog\/tag\/nervo-hipoglosso\/","url":"https:\/\/www.codental.com.br\/blog\/tag\/nervo-hipoglosso\/","name":"Arquivos Nervo hipoglosso - Codental Blog","isPartOf":{"@id":"https:\/\/www.codental.com.br\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/www.codental.com.br\/blog\/tag\/nervo-hipoglosso\/#breadcrumb"},"inLanguage":"pt-BR"},{"@type":"BreadcrumbList","@id":"https:\/\/www.codental.com.br\/blog\/tag\/nervo-hipoglosso\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.codental.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Nervo hipoglosso"}]},{"@type":"WebSite","@id":"https:\/\/www.codental.com.br\/blog\/#website","url":"https:\/\/www.codental.com.br\/blog\/","name":"Codental Blog","description":"Artigos e not\u00edcias sobre odontologia","publisher":{"@id":"https:\/\/www.codental.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.codental.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.codental.com.br\/blog\/#organization","name":"Codental","url":"https:\/\/codental.com.br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.codental.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.codental.com.br\/blog\/wp-content\/uploads\/2018\/10\/logo.png","contentUrl":"https:\/\/www.codental.com.br\/blog\/wp-content\/uploads\/2018\/10\/logo.png","width":1200,"height":300,"caption":"Codental"},"image":{"@id":"https:\/\/www.codental.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/www.facebook.com\/codentalbr","https:\/\/x.com\/CodentalBr","https:\/\/www.instagram.com\/codentalbr\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.codental.com.br\/blog\/wp-json\/wp\/v2\/tags\/619","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.codental.com.br\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.codental.com.br\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.codental.com.br\/blog\/wp-json\/wp\/v2\/posts?tags=619"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}