{"id":3760,"date":"2023-06-15T17:00:00","date_gmt":"2023-06-15T20:00:00","guid":{"rendered":"https:\/\/www.codental.com.br\/blog\/?p=3760"},"modified":"2023-06-15T08:55:43","modified_gmt":"2023-06-15T11:55:43","slug":"mau-halito-uma-abordagem-completa","status":"publish","type":"post","link":"https:\/\/www.codental.com.br\/blog\/mau-halito-uma-abordagem-completa\/","title":{"rendered":"Mau h\u00e1lito: uma abordagem completa"},"content":{"rendered":"\n<p>O <strong>mau h\u00e1lito<\/strong>, conhecido clinicamente como <a href=\"https:\/\/www.codental.com.br\/blog\/halitose-causas-sintomas-e-tratamentos\/?utm_source=blog&utm_medium=referral&utm_content=mau-halito-uma-abordagem-completa\">halitose<\/a>, afeta muitas pessoas em todo o mundo. <\/p>\n\n\n\n<p>Embora seja uma condi\u00e7\u00e3o comum, o mau h\u00e1lito tem impacto significativo na qualidade de vida do indiv\u00edduo, afetando sua autoestima, al\u00e9m de suas rela\u00e7\u00f5es interpessoais.<\/p>\n\n\n\n<p>Al\u00e9m disso, o paciente n\u00e3o percebe o mau h\u00e1lito, devido a mecanismos org\u00e2nicos que discorreremos abaixo.<\/p>\n\n\n\n<p>Por fim, este artigo esclarecer\u00e1 a origem, causa e tratamento do mau h\u00e1lito, bem como consistir\u00e1 em um guia orientador quanto a origem oral, ou do est\u00f4mago, sobre halitose.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Qual a origem do mau h\u00e1lito?<\/h2>\n\n\n\n<p>O mau h\u00e1lito \u00e9 uma condi\u00e7\u00e3o caracterizada pelo odor desagrad\u00e1vel proveniente da cavidade oral.<\/p>\n\n\n\n<p>Embora sua origem seja uma quest\u00e3o duvidosa tanto para dentistas, como para pacientes, o mau cheiro \u00e9 proveniente da cavidade oral, geralmente.<\/p>\n\n\n\n<p>Logo, considera-se a l\u00edngua como o local mais comum da origem do problema.<\/p>\n\n\n\n<p>Isso se deve \u00e0s caracter\u00edsticas morfol\u00f3gicas da l\u00edngua, onde seu revestimento consiste na exist\u00eancia de papilas, cuja fun\u00e7\u00e3o \u00e9 levar informa\u00e7\u00f5es ao c\u00e9rebro acerca da identifica\u00e7\u00e3o dos sabores dos alimentos.<\/p>\n\n\n\n<p>Entre as papilas existem pequenas criptas que favorecem o ac\u00famulo de restos alimentares, al\u00e9m de abrigarem restos epiteliais que descamam da l\u00edngua.<\/p>\n\n\n\n<p>Consequentemente, a exist\u00eancia dessas part\u00edculas nas criptas entre as papilas, servem de meio de cultura bacteriano, provocando assim, o mau h\u00e1lito. <\/p>\n\n\n\n<h2 class=\"wp-block-heading\">O que pode causar mau h\u00e1lito?<\/h2>\n\n\n\n<p>Existem in\u00fameras causas poss\u00edveis para a halitose, dentre eles, fatores bucais e n\u00e3o bucais.<\/p>\n\n\n\n<p><strong>As causas mais comuns est\u00e3o relacionadas \u00e0 m\u00e1 higiene <\/strong>como, por exemplo: doen\u00e7as <a href=\"https:\/\/www.codental.com.br\/blog\/periodontite-avancada\/?utm_source=blog&utm_medium=referral&utm_content=mau-halito-uma-abordagem-completa\">periodontais<\/a>, <a href=\"https:\/\/www.codental.com.br\/blog\/carie-inicial-entenda-tudo-sobre-esse-problema\/?utm_source=blog&utm_medium=referral&utm_content=mau-halito-uma-abordagem-completa\">c\u00e1ries<\/a>, saburra lingual e infe\u00e7\u00f5es orais.<\/p>\n\n\n\n<p>Por outro lado, as causas n\u00e3o bucais, associam-se a condi\u00e7\u00f5es respirat\u00f3rias, dist\u00farbios gastrointestinais, medicamentos, dieta, tabagismo, e condi\u00e7\u00f5es sist\u00eamicas como diabete e insufici\u00eancia renal.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Mau h\u00e1lito causado por doen\u00e7as periodontais<\/h3>\n\n\n\n<p>O <strong>ac\u00famulo bacteriano causador do t\u00e1rtaro<\/strong> e, consequentemente da <strong>doen\u00e7a periodontal, influ\u00eancia na ocorr\u00eancia de mau h\u00e1lito.<\/strong><\/p>\n\n\n\n<p>Isso se deve \u00e0 presen\u00e7a do ac\u00famulo de restos alimentares e salivares que, ao alterarem o pH do meio bucal, favorecem o surgimento da matriz bacteriana.<\/p>\n\n\n\n<p>Com o crescimento desta matriz (o t\u00e1rtaro), na regi\u00e3o cervical e interproximal dos dentes, ocorre a cascata inflamat\u00f3ria, aumentando assim, o volume bacteriano e consequentemente o mau h\u00e1lito.<\/p>\n\n\n\n<p>Contudo, a pr\u00f3pria altera\u00e7\u00e3o do pH salivar e dos componentes oriundos deste, favorecem a incid\u00eancia de halitose.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Mau h\u00e1lito devido \u00e0 C\u00e1rie dent\u00e1ria<\/h3>\n\n\n\n<p>Do mesmo modo que <strong>o mau h\u00e1lito relaciona-se com o meio de cultura bacteriano<\/strong>, a c\u00e1rie \u00e9 proveniente da bact\u00e9ria <em>Streptococcus mutans<\/em> presente no esmalte.<\/p>\n\n\n\n<p>Logo, a presen\u00e7a deste agente etiol\u00f3gico \u00e9 fator para a exist\u00eancia de mau h\u00e1lito, al\u00e9m de contribuir para a piora deste estado. <\/p>\n\n\n\n<p>Portanto, o tratamento restaurador, eliminando a presen\u00e7a das bact\u00e9rias causadas pela c\u00e1rie dent\u00e1ria, existe como agente remissivo do mau h\u00e1lito.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Mau h\u00e1lito causado por infec\u00e7\u00f5es orais<\/h3>\n\n\n\n<p>Os <strong>quadros inflamat\u00f3rios que acometem a cavidade oral <\/strong>como a tonsilite, por exemplo, causam mau h\u00e1lito.<\/p>\n\n\n\n<p>Isso deve a presen\u00e7a de bact\u00e9rias pat\u00f3genas, que alteram a condi\u00e7\u00e3o saud\u00e1vel deste meio, gerando assim, odores desagrad\u00e1veis no meio bucal.<\/p>\n\n\n\n<p>Consequentemente, o uso de medicamentos visando o reestabelecimento da microbiota saud\u00e1vel bucal, extingue o mau h\u00e1lito, bem como seu odor desagrad\u00e1vel.<\/p>\n\n\n\n<p>Vale ressaltar que o uso de antibioticoterapia inibe a replica\u00e7\u00e3o bacteriana. Isso quer dizer que, ao mesmo tempo que elimina o pat\u00f3geno, o faz com a microbiota saud\u00e1vel existente se altere.<\/p>\n\n\n\n<p>Portanto, cuidados p\u00f3s-tratamento para ideal reestabelecimento da flora bacteriana, diminui as chances de recidiva.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"> Mau h\u00e1lito causado por saburra lingual<\/h3>\n\n\n\n<p>A l\u00edngua possui diversas papilas gustativas, assim como foi dito acima. Al\u00e9m disso, as criptas papilares existentes, apresentam-se como dep\u00f3sitos de:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Restos alimentares;<\/li><li>C\u00e9lulas epiteliais descamadas e <\/li><li>Placas bacterianas.<\/li><\/ul>\n\n\n\n<p>Diante da presen\u00e7a destes compostos, ocorre a <strong>fermenta\u00e7\u00e3o destes<\/strong>, que come\u00e7am a liberar <strong>odores de enxofre<\/strong>.<\/p>\n\n\n\n<p>Logo, a saburra lingual, especialmente <strong>relacionada a hipossaliva\u00e7\u00e3o, gera mau h\u00e1lito e odores desagrad\u00e1veis ao paciente.<\/strong><\/p>\n\n\n\n<p>Assim como ocorre a halitose na presen\u00e7a da saburra lingual, ao dormirmos, ocorre uma diminui\u00e7\u00e3o fisiol\u00f3gica natural da saliva\u00e7\u00e3o.<\/p>\n\n\n\n<p>Consequentemente a baixa produ\u00e7\u00e3o salivar gera aumento na fermenta\u00e7\u00e3o bucal, causando o comum mau cheiro pela manh\u00e3.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Xerostomia<\/h4>\n\n\n\n<p>A xerostomia tem etiologia na baixa produ\u00e7\u00e3o salivar, contudo, est\u00e1 relacionada a fatores bucais, sist\u00eamicos, medicamentosos, ou de ingest\u00e3o h\u00eddrica.<\/p>\n\n\n\n<p>Pacientes portadores de S\u00edndrome de Down, por exemplo, pela pr\u00f3pria condi\u00e7\u00e3o, apresentam xerostomia caracter\u00edstica da pr\u00f3pria condi\u00e7\u00e3o.<\/p>\n\n\n\n<p>Logo, s\u00e3o mais suscept\u00edveis a presen\u00e7a de mau h\u00e1lito, requerendo maiores cuidados na manuten\u00e7\u00e3o da higiene oral.<\/p>\n\n\n\n<p>Ademais, a administra\u00e7\u00e3o de certos f\u00e1rmacos, causam xerostomia, propiciando a ocorr\u00eancia de halitose.<\/p>\n\n\n\n<p>Os problemas respirat\u00f3rios causados em decorr\u00eancia de inflama\u00e7\u00f5es e infec\u00e7\u00f5es, diminuem o fluxo salivar levando \u00e0 xerostomia e ao odor desagrad\u00e1vel da cavidade oral.<\/p>\n\n\n\n<p>Por fim, e causa muito comum de mau h\u00e1lito, a xerostomia origin\u00e1ria da falta de ingest\u00e3o de l\u00edquidos que, al\u00e9m de gerar a sensa\u00e7\u00e3o de boca seca, propicia ao desenvolvimento de odores desagrad\u00e1veis da cavidade bucal;<\/p>\n\n\n\n<p>O cuidado requer a avalia\u00e7\u00e3o do especialista, onde, diante do diagn\u00f3stico adequado, orienta e adequa ao paciente o reestabelecimento saud\u00e1vel deste paciente.<\/p>\n\n\n\n<p>Al\u00e9m disso, alguns casos diminuem ou regridem a halitose com a administra\u00e7\u00e3o de saliva artificial, melhorando assim a qualidade de vida e intera\u00e7\u00f5es sociais do paciente.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Mau h\u00e1lito causado por m\u00e1 higiene<\/h2>\n\n\n\n<p><strong>A mais comum causa de mau h\u00e1lito no mundo relaciona-se com a higiene inadequada<\/strong> ou inexistente do paciente.<\/p>\n\n\n\n<p>Isso se deve a falha ou falta de remo\u00e7\u00e3o de agentes causadores de fermenta\u00e7\u00e3o bacteriana da parte do indiv\u00edduo.<\/p>\n\n\n\n<p>O tratamento inclui medidas preventivas de promo\u00e7\u00e3o de sa\u00fade bucal, al\u00e9m de tratamentos mais invasivos como a remo\u00e7\u00e3o mec\u00e2nica de placa bacteriana por ponta ultrass\u00f4nica ou instrumentais de raspagem manual.<\/p>\n\n\n\n<p>Tamb\u00e9m \u00e9 aconselhado ao paciente o uso de enxaguante bucal, al\u00e9m do uso de fio dental, ap\u00f3s as refei\u00e7\u00f5es, e ainda correta escova\u00e7\u00e3o.<\/p>\n\n\n\n<p>Al\u00e9m disso, o profissional deve demonstrar e ensinar ao paciente a correta forma de escova\u00e7\u00e3o dental a fim da melhora acerca do autocuidado executado pelo paciente em casa.<\/p>\n\n\n\n<p>Por fim, para que a m\u00e1 higiene deixe de ser o fator etiol\u00f3gico causador do mau h\u00e1lito bucal do paciente, \u00e9 de suma import\u00e2ncia que o profissional conquiste a ades\u00e3o deste, \u00e0 pr\u00e1tica correta de higiene oral a fim de evitar recidivas.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Mau h\u00e1lito causado por fatores sist\u00eamicos<\/h2>\n\n\n\n<p>Para tratar o mau h\u00e1lito proveniente de patologias sist\u00eamicas, o dentista deve incluir o paciente em cuidados multidisciplinares.<\/p>\n\n\n\n<p>O trabalho em conjunto com o m\u00e9dico assistente, propicia o diagn\u00f3stico diferencial e atende a individualidade do quadro deste paciente. <\/p>\n\n\n\n<p>Logo, tais medidas devem ofertar ao paciente melhora do quadro ou remiss\u00e3o dos sintomas incluindo melhora da qualidade de vida deste.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Como tratar o mau h\u00e1lito?<\/h2>\n\n\n\n<p>O tratamento do mau h\u00e1lito requer o diagn\u00f3stico do dentista.<\/p>\n\n\n\n<p>Embora o mau h\u00e1lito seja comum, alguns exames auxiliam na busca da causa e tratamento deste incomodo. <\/p>\n\n\n\n<p>Alguns exemplos incluem os seguintes exames diagn\u00f3sticos:<\/p>\n\n\n\n<ol class=\"wp-block-list\"><li>Avalia\u00e7\u00e3o do odor exalado;<\/li><li>A medi\u00e7\u00e3o do fluxo salivar;<\/li><li>A an\u00e1lise do h\u00e1lito por cromatografia gasosa;<\/li><li>An\u00e1lise microbiol\u00f3gica mediante cultura da saliva e saburra lingual;<\/li><li>Exames radiogr\u00e1ficos e;<\/li><li>Exames complementares para investigar causas sist\u00eamicas.<\/li><\/ol>\n\n\n\n<p>\u00c9 importante ressaltar que <strong>tratamentos caseiros sem a avalia\u00e7\u00e3o do dentista podem piorar<\/strong> o desconforto causado pelo mau h\u00e1lito.<\/p>\n\n\n\n<p>Al\u00e9m disso, a falta de diagn\u00f3stico pode inferir um tratamento inadequado ao paciente. Portanto, a consulta ao dentista para investigar as causas do mau h\u00e1lito \u00e9 essencial.<\/p>\n\n\n\n<p>Por fim, vale ressaltar que a <strong>correta higiene bucal<\/strong>, contemplando a escova\u00e7\u00e3o, uso de fio dental e raspador de l\u00edngua, <strong>diminui exponencialmente a exist\u00eancia de mau h\u00e1lito<\/strong> no paciente, facilitando o diagn\u00f3stico diferencial caso haja presen\u00e7a de odores desagrad\u00e1veis neste.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O mau h\u00e1lito, conhecido clinicamente como halitose, afeta muitas pessoas em todo o mundo&#8230;.<\/p>\n","protected":false},"author":30,"featured_media":3941,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_target_audience":"","footnotes":""},"categories":[247],"tags":[478,479],"class_list":["post-3760","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-doencas-odontologicas","tag-halitose","tag-mau-halito"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mau h\u00e1lito: uma abordagem completa<\/title>\n<meta name=\"description\" content=\"O mau h\u00e1lito, conhecido clinicamente como halitose, afeta muitas pessoas em todo o mundo, afetando a vida dos pacientes. Confira!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.codental.com.br\/blog\/mau-halito-uma-abordagem-completa\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mau h\u00e1lito: uma abordagem completa\" \/>\n<meta property=\"og:description\" content=\"O mau h\u00e1lito, conhecido clinicamente como halitose, afeta muitas pessoas em todo o mundo, afetando a vida dos pacientes. Confira!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.codental.com.br\/blog\/mau-halito-uma-abordagem-completa\/\" \/>\n<meta property=\"og:site_name\" content=\"Codental Blog\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.com\/codentalbr\" \/>\n<meta property=\"article:published_time\" content=\"2023-06-15T20:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.codental.com.br\/blog\/wp-content\/uploads\/2023\/06\/mau-halito.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1010\" \/>\n\t<meta property=\"og:image:height\" content=\"550\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Jaqueline\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@CodentalBr\" \/>\n<meta name=\"twitter:site\" content=\"@CodentalBr\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jaqueline\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.codental.com.br\/blog\/mau-halito-uma-abordagem-completa\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.codental.com.br\/blog\/mau-halito-uma-abordagem-completa\/\"},\"author\":{\"name\":\"Jaqueline\",\"@id\":\"https:\/\/www.codental.com.br\/blog\/#\/schema\/person\/7506ab8d7a0b35cdfe68fae4ee2f9277\"},\"headline\":\"Mau h\u00e1lito: uma abordagem completa\",\"datePublished\":\"2023-06-15T20:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.codental.com.br\/blog\/mau-halito-uma-abordagem-completa\/\"},\"wordCount\":1418,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.codental.com.br\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.codental.com.br\/blog\/mau-halito-uma-abordagem-completa\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.codental.com.br\/blog\/wp-content\/uploads\/2023\/06\/mau-halito.jpg\",\"keywords\":[\"Halitose\",\"mau h\u00e1lito\"],\"articleSection\":[\"Doen\u00e7as odontol\u00f3gicas\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.codental.com.br\/blog\/mau-halito-uma-abordagem-completa\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.codental.com.br\/blog\/mau-halito-uma-abordagem-completa\/\",\"url\":\"https:\/\/www.codental.com.br\/blog\/mau-halito-uma-abordagem-completa\/\",\"name\":\"Mau h\u00e1lito: uma abordagem completa\",\"isPartOf\":{\"@id\":\"https:\/\/www.codental.com.br\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.codental.com.br\/blog\/mau-halito-uma-abordagem-completa\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.codental.com.br\/blog\/mau-halito-uma-abordagem-completa\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.codental.com.br\/blog\/wp-content\/uploads\/2023\/06\/mau-halito.jpg\",\"datePublished\":\"2023-06-15T20:00:00+00:00\",\"description\":\"O mau h\u00e1lito, conhecido clinicamente como halitose, afeta muitas pessoas em todo o mundo, afetando a vida dos pacientes. Confira!\",\"breadcrumb\":{\"@id\":\"https:\/\/www.codental.com.br\/blog\/mau-halito-uma-abordagem-completa\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.codental.com.br\/blog\/mau-halito-uma-abordagem-completa\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.codental.com.br\/blog\/mau-halito-uma-abordagem-completa\/#primaryimage\",\"url\":\"https:\/\/www.codental.com.br\/blog\/wp-content\/uploads\/2023\/06\/mau-halito.jpg\",\"contentUrl\":\"https:\/\/www.codental.com.br\/blog\/wp-content\/uploads\/2023\/06\/mau-halito.jpg\",\"width\":1010,\"height\":550,\"caption\":\"mau h\u00e1lito\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.codental.com.br\/blog\/mau-halito-uma-abordagem-completa\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.codental.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mau h\u00e1lito: uma abordagem completa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.codental.com.br\/blog\/#website\",\"url\":\"https:\/\/www.codental.com.br\/blog\/\",\"name\":\"Codental Blog\",\"description\":\"Artigos e not\u00edcias sobre odontologia\",\"publisher\":{\"@id\":\"https:\/\/www.codental.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.codental.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.codental.com.br\/blog\/#organization\",\"name\":\"Codental\",\"url\":\"https:\/\/codental.com.br\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.codental.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.codental.com.br\/blog\/wp-content\/uploads\/2018\/10\/logo.png\",\"contentUrl\":\"https:\/\/www.codental.com.br\/blog\/wp-content\/uploads\/2018\/10\/logo.png\",\"width\":1200,\"height\":300,\"caption\":\"Codental\"},\"image\":{\"@id\":\"https:\/\/www.codental.com.br\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"http:\/\/www.facebook.com\/codentalbr\",\"https:\/\/x.com\/CodentalBr\",\"https:\/\/www.instagram.com\/codentalbr\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.codental.com.br\/blog\/#\/schema\/person\/7506ab8d7a0b35cdfe68fae4ee2f9277\",\"name\":\"Jaqueline\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.codental.com.br\/blog\/wp-content\/uploads\/2022\/11\/WhatsApp-Image-2022-11-23-at-18.30.21-343x240.jpeg\",\"url\":\"https:\/\/www.codental.com.br\/blog\/wp-content\/uploads\/2022\/11\/WhatsApp-Image-2022-11-23-at-18.30.21-343x240.jpeg\",\"contentUrl\":\"https:\/\/www.codental.com.br\/blog\/wp-content\/uploads\/2022\/11\/WhatsApp-Image-2022-11-23-at-18.30.21-343x240.jpeg\",\"caption\":\"Jaqueline\"},\"description\":\"Mineira, 38 anos. Dentista cl\u00ednica geral e jornalista. Apaixonada por artes, m\u00fasica e culin\u00e1ria, um trio perfeito para bons encontros com os amigos.\",\"url\":\"https:\/\/www.codental.com.br\/blog\/author\/jackeline\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mau h\u00e1lito: uma abordagem completa","description":"O mau h\u00e1lito, conhecido clinicamente como halitose, afeta muitas pessoas em todo o mundo, afetando a vida dos pacientes. Confira!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.codental.com.br\/blog\/mau-halito-uma-abordagem-completa\/","og_locale":"pt_BR","og_type":"article","og_title":"Mau h\u00e1lito: uma abordagem completa","og_description":"O mau h\u00e1lito, conhecido clinicamente como halitose, afeta muitas pessoas em todo o mundo, afetando a vida dos pacientes. Confira!","og_url":"https:\/\/www.codental.com.br\/blog\/mau-halito-uma-abordagem-completa\/","og_site_name":"Codental Blog","article_publisher":"http:\/\/www.facebook.com\/codentalbr","article_published_time":"2023-06-15T20:00:00+00:00","og_image":[{"width":1010,"height":550,"url":"https:\/\/www.codental.com.br\/blog\/wp-content\/uploads\/2023\/06\/mau-halito.jpg","type":"image\/jpeg"}],"author":"Jaqueline","twitter_card":"summary_large_image","twitter_creator":"@CodentalBr","twitter_site":"@CodentalBr","twitter_misc":{"Escrito por":"Jaqueline","Est. tempo de leitura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.codental.com.br\/blog\/mau-halito-uma-abordagem-completa\/#article","isPartOf":{"@id":"https:\/\/www.codental.com.br\/blog\/mau-halito-uma-abordagem-completa\/"},"author":{"name":"Jaqueline","@id":"https:\/\/www.codental.com.br\/blog\/#\/schema\/person\/7506ab8d7a0b35cdfe68fae4ee2f9277"},"headline":"Mau h\u00e1lito: uma abordagem completa","datePublished":"2023-06-15T20:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.codental.com.br\/blog\/mau-halito-uma-abordagem-completa\/"},"wordCount":1418,"commentCount":0,"publisher":{"@id":"https:\/\/www.codental.com.br\/blog\/#organization"},"image":{"@id":"https:\/\/www.codental.com.br\/blog\/mau-halito-uma-abordagem-completa\/#primaryimage"},"thumbnailUrl":"https:\/\/www.codental.com.br\/blog\/wp-content\/uploads\/2023\/06\/mau-halito.jpg","keywords":["Halitose","mau h\u00e1lito"],"articleSection":["Doen\u00e7as odontol\u00f3gicas"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.codental.com.br\/blog\/mau-halito-uma-abordagem-completa\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.codental.com.br\/blog\/mau-halito-uma-abordagem-completa\/","url":"https:\/\/www.codental.com.br\/blog\/mau-halito-uma-abordagem-completa\/","name":"Mau h\u00e1lito: uma abordagem completa","isPartOf":{"@id":"https:\/\/www.codental.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.codental.com.br\/blog\/mau-halito-uma-abordagem-completa\/#primaryimage"},"image":{"@id":"https:\/\/www.codental.com.br\/blog\/mau-halito-uma-abordagem-completa\/#primaryimage"},"thumbnailUrl":"https:\/\/www.codental.com.br\/blog\/wp-content\/uploads\/2023\/06\/mau-halito.jpg","datePublished":"2023-06-15T20:00:00+00:00","description":"O mau h\u00e1lito, conhecido clinicamente como halitose, afeta muitas pessoas em todo o mundo, afetando a vida dos pacientes. Confira!","breadcrumb":{"@id":"https:\/\/www.codental.com.br\/blog\/mau-halito-uma-abordagem-completa\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.codental.com.br\/blog\/mau-halito-uma-abordagem-completa\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.codental.com.br\/blog\/mau-halito-uma-abordagem-completa\/#primaryimage","url":"https:\/\/www.codental.com.br\/blog\/wp-content\/uploads\/2023\/06\/mau-halito.jpg","contentUrl":"https:\/\/www.codental.com.br\/blog\/wp-content\/uploads\/2023\/06\/mau-halito.jpg","width":1010,"height":550,"caption":"mau h\u00e1lito"},{"@type":"BreadcrumbList","@id":"https:\/\/www.codental.com.br\/blog\/mau-halito-uma-abordagem-completa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.codental.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Mau h\u00e1lito: uma abordagem completa"}]},{"@type":"WebSite","@id":"https:\/\/www.codental.com.br\/blog\/#website","url":"https:\/\/www.codental.com.br\/blog\/","name":"Codental Blog","description":"Artigos e not\u00edcias sobre odontologia","publisher":{"@id":"https:\/\/www.codental.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.codental.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.codental.com.br\/blog\/#organization","name":"Codental","url":"https:\/\/codental.com.br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.codental.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.codental.com.br\/blog\/wp-content\/uploads\/2018\/10\/logo.png","contentUrl":"https:\/\/www.codental.com.br\/blog\/wp-content\/uploads\/2018\/10\/logo.png","width":1200,"height":300,"caption":"Codental"},"image":{"@id":"https:\/\/www.codental.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/www.facebook.com\/codentalbr","https:\/\/x.com\/CodentalBr","https:\/\/www.instagram.com\/codentalbr\/"]},{"@type":"Person","@id":"https:\/\/www.codental.com.br\/blog\/#\/schema\/person\/7506ab8d7a0b35cdfe68fae4ee2f9277","name":"Jaqueline","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.codental.com.br\/blog\/wp-content\/uploads\/2022\/11\/WhatsApp-Image-2022-11-23-at-18.30.21-343x240.jpeg","url":"https:\/\/www.codental.com.br\/blog\/wp-content\/uploads\/2022\/11\/WhatsApp-Image-2022-11-23-at-18.30.21-343x240.jpeg","contentUrl":"https:\/\/www.codental.com.br\/blog\/wp-content\/uploads\/2022\/11\/WhatsApp-Image-2022-11-23-at-18.30.21-343x240.jpeg","caption":"Jaqueline"},"description":"Mineira, 38 anos. Dentista cl\u00ednica geral e jornalista. Apaixonada por artes, m\u00fasica e culin\u00e1ria, um trio perfeito para bons encontros com os amigos.","url":"https:\/\/www.codental.com.br\/blog\/author\/jackeline\/"}]}},"_links":{"self":[{"href":"https:\/\/www.codental.com.br\/blog\/wp-json\/wp\/v2\/posts\/3760","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.codental.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.codental.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.codental.com.br\/blog\/wp-json\/wp\/v2\/users\/30"}],"replies":[{"embeddable":true,"href":"https:\/\/www.codental.com.br\/blog\/wp-json\/wp\/v2\/comments?post=3760"}],"version-history":[{"count":10,"href":"https:\/\/www.codental.com.br\/blog\/wp-json\/wp\/v2\/posts\/3760\/revisions"}],"predecessor-version":[{"id":3944,"href":"https:\/\/www.codental.com.br\/blog\/wp-json\/wp\/v2\/posts\/3760\/revisions\/3944"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.codental.com.br\/blog\/wp-json\/wp\/v2\/media\/3941"}],"wp:attachment":[{"href":"https:\/\/www.codental.com.br\/blog\/wp-json\/wp\/v2\/media?parent=3760"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.codental.com.br\/blog\/wp-json\/wp\/v2\/categories?post=3760"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.codental.com.br\/blog\/wp-json\/wp\/v2\/tags?post=3760"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}